{"id":15930,"date":"2016-07-08T04:36:42","date_gmt":"2016-07-08T04:36:42","guid":{"rendered":"http:\/\/www.pricepony.com.br\/blog\/?p=15930"},"modified":"2016-07-08T04:36:42","modified_gmt":"2016-07-08T04:36:42","slug":"huawei-honor-8-max-vs-xiaomi-mi-max","status":"publish","type":"post","link":"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/","title":{"rendered":"Huawei Honor 8 Max VS Xiaomi Mi Max"},"content":{"rendered":"<p><strong>Huawei Honor 8 Max foi visto na TENAA recentemente e parece que ele ser\u00e1 o concorrente do Xiaomi Mi Max. Ent\u00e3o, vamos fazer uma compara\u00e7\u00e3o entre o Huawei Honor 8 Max VS Xiaomi Mi Max.<\/strong><\/p><div style=\"float: none; display: block; margin: 0 -10px; text-align: center;\"><!-- Top Banner PH NEW -->\n                        <ins class=\"adsbygoogle\"\n                             style=\"display:inline-block;width:728px;height:90px\"\n                             data-ad-client=\"ca-pub-4796993490224996\"\n                             data-ad-slot=\"9195989669\"><\/ins>\n                        <script>(adsbygoogle = window.adsbygoogle || []).push({});<\/script><\/div><\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-23471\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/www.pricepony.com.my\/blog\/wp-content\/uploads\/2016\/07\/Huawei-Honor-V8-Max-VS-Xiaomi-Mi-Max.jpg\" alt=\"Huawei Honor 8 Max VS Xiaomi Mi Max\" width=\"375\" height=\"250\" \/ \/><\/p>\n<h3><strong>Huawei Honor 8 Max VS Xiaomi Mi Max: a batalha dos phablets!<\/strong><\/h3>\n<p>O Huawei Honor 8 Max VS Xiaomi Mi Max possuem tela de phablet, assim como seus pr\u00f3prios nomes. Huawei Honor 8 Max possui uma tela de 6,6 polegadas, que \u00e9 um pouco maior do que a tela full HD de 6,4 polegadas do Xiaomi Mi Max. Al\u00e9m disso, o Huawei Honor 8 Max possui capacidade QuadHD AMOLED o que \u00e9 aparentemente mais animador do que o IPS LCD touchscreen do Xiaomi Mi Max. Isso \u00e9 sobre as telas, mas e sobre os componentes?<\/p>\n<p>As especifica\u00e7\u00f5es do Xiaomi Mi Max provavelmente ganham nesta categoria. O smartphone Xiaomi possui variantes de chipsets quem consistem em um Qualcomm Snapdragon 650 e Qualcomm Snapdragon 652. Respectivamente os processadores tamb\u00e9m variam, incluindo um \u00a0Quad-core de 1,4 GHz e um Dual-core de 1,8 GHz para a vers\u00e3o 650. Enquanto isso, a Huawei Honor 8 Max possui um chipset Kirin 950 com um processador octa-core de 2.3GHz.<\/p>\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div class=\"715bb7587c5240ca50b41debac6fc6bc\" data-index=\"2\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!-- BR Middle -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:336px;height:280px\"\r\n     data-ad-client=\"ca-pub-4796993490224996\"\r\n     data-ad-slot=\"2407662860\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n\n<p><img decoding=\"async\" class=\"aligncenter wp-image-23473\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"http:\/\/www.pricepony.com.my\/blog\/wp-content\/uploads\/2016\/07\/Huawei-Honor-V8-Max-VS-Xiaomi-Mi-Max2.jpg\" alt=\"Huawei Honor 8 Max VS Xiaomi Mi Max\" width=\"333\" height=\"250\" \/ \/><\/p>\n<p>O Huawei Honor 8 Max vem com 3GB de RAM e 32GB de ROM, que s\u00e3o semelhantes a uma das vers\u00f5es do Xiaomi Mi Max. Al\u00e9m disso, o smartphone Xiaomi tamb\u00e9m possui uma outra vers\u00e3o de 4GB de RAM, com 128GB de ROM. O concorrente do Huawei Honor 8 Max parece continuar sendo o vencedor com sua bateria de 4850 mAh. J\u00e1 a bateria do Huawei Honor 8 Max \u00e9 um pouco menor, com 4000 mAh de capacidade.<\/p>\n<h3><strong>Huawei Honor 8 Max VS Xiaomi Mi Max: Pre\u00e7o e data de lan\u00e7amento<\/strong><\/h3>\n<p>Parece dif\u00edcil escolher o vencedor na categoria c\u00e2mera, j\u00e1 que na batalha Huawei Honor 8 Max VS Xiaomi Mi Max as c\u00e2meras dos dois celulares s\u00e3o muito boas com 13MP\/8MP e 16MP\/5MP respectivamente. O Xiaomi Mi Max foi lan\u00e7ado no m\u00eas passado e ele j\u00e1 est\u00e1 dispon\u00edvel por aproximadamente R$960,00. Quanto ao Huawei Honor 8 Max, sua data de lan\u00e7amento e pre\u00e7o ainda s\u00e3o segredos.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Huawei Honor 8 Max foi visto na TENAA recentemente e parece que ele ser\u00e1 o concorrente do Xiaomi Mi Max. Ent\u00e3o, vamos fazer uma compara\u00e7\u00e3o entre o Huawei Honor 8 Max VS Xiaomi Mi Max. Huawei Honor 8 Max VS Xiaomi Mi Max: a batalha dos phablets! O Huawei Honor 8 Max VS Xiaomi Mi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[207,201],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.0.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Huawei Honor 8 Max VS Xiaomi Mi Max - Price Pony<\/title>\n<meta name=\"description\" content=\"Huawei Honor 8 Max foi visto na TENAA recentemente e parece que ele ser\u00e1 o concorrente do Xiaomi Mi Max... Huawei Honor 8 Max VS Xiaomi Mi Max.\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huawei Honor 8 Max VS Xiaomi Mi Max - Price Pony\" \/>\n<meta property=\"og:description\" content=\"Huawei Honor 8 Max foi visto na TENAA recentemente e parece que ele ser\u00e1 o concorrente do Xiaomi Mi Max... Huawei Honor 8 Max VS Xiaomi Mi Max.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\" \/>\n<meta property=\"og:site_name\" content=\"Price Pony\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-08T04:36:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pricepony.com.br\/blog\/wp-content\/uploads\/2016\/07\/Huawei-Honor-V8-Max-VS-Xiaomi-Mi-Max1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/#website\",\"url\":\"https:\/\/www.pricepony.com.br\/blog\/\",\"name\":\"Price Pony\",\"description\":\"www.pricepony.com.br\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.pricepony.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.pricepony.com.br\/blog\/wp-content\/uploads\/2016\/07\/Huawei-Honor-V8-Max-VS-Xiaomi-Mi-Max1.jpg\",\"width\":960,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/#webpage\",\"url\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\",\"name\":\"Huawei Honor 8 Max VS Xiaomi Mi Max - Price Pony\",\"isPartOf\":{\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/#primaryimage\"},\"datePublished\":\"2016-07-08T04:36:42+00:00\",\"dateModified\":\"2016-07-08T04:36:42+00:00\",\"author\":{\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/#\/schema\/person\/c338807e08d2e0642a2680633342a0b6\"},\"description\":\"Huawei Honor 8 Max foi visto na TENAA recentemente e parece que ele ser\\u00e1 o concorrente do Xiaomi Mi Max... Huawei Honor 8 Max VS Xiaomi Mi Max.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/\",\"url\":\"https:\/\/www.pricepony.com.br\/blog\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\",\"url\":\"https:\/\/www.pricepony.com.br\/blog\/huawei-honor-8-max-vs-xiaomi-mi-max\/\",\"name\":\"Huawei Honor 8 Max VS Xiaomi Mi Max\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/#\/schema\/person\/c338807e08d2e0642a2680633342a0b6\",\"name\":\"Chris Eilers\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.pricepony.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/83e51b46626e1e91aba06adcb3bf3473?s=96&d=mm&r=g\",\"caption\":\"Chris Eilers\"},\"description\":\"Chris is an experienced Digital Marketer and Growth Hacker with work experience in Mckinsey Germany and Rocket Internet Asia. He is the CEO of Oizoioi Malaysia and actively engaged in the Startup Scene in South East Asia.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/posts\/15930"}],"collection":[{"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/comments?post=15930"}],"version-history":[{"count":0,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/posts\/15930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/media\/15931"}],"wp:attachment":[{"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/media?parent=15930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/categories?post=15930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pricepony.com.br\/blog\/wp-json\/wp\/v2\/tags?post=15930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}